{"id":748,"date":"2023-05-19T14:55:00","date_gmt":"2023-05-19T18:55:00","guid":{"rendered":"http:\/\/westnipissing.ca\/?page_id=748"},"modified":"2026-05-12T10:13:00","modified_gmt":"2026-05-12T14:13:00","slug":"benevole","status":"publish","type":"page","link":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/","title":{"rendered":"Devenez b\u00e9n\u00e9vole"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"748\" class=\"elementor elementor-748 elementor-542\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c678222 e-con-full e-flex e-con e-parent\" data-id=\"c678222\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-dce-background-image-url=\"https:\/\/westnipissing.ca\/wp-content\/uploads\/2025\/04\/AdobeStock_291462034-1024x576-1.jpeg\" class=\"elementor-element elementor-element-063272b e-con-full e-flex e-con e-child\" data-id=\"063272b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e414564 e-con-full e-flex e-con e-child\" data-id=\"e414564\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1be029f elementor-widget elementor-widget-text-editor\" data-id=\"1be029f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"wp-block-heading\">Participez et invitez des amis!<\/h4>\n<p>Que vous soyez un \u00e9tudiant du secondaire souhaitant accomplir des heures communautaires ou quelqu\u2019un \u00e0 la retraite qui aimerait s\u2019impliquer dans la communaut\u00e9, nous avons de nombreuses options de b\u00e9n\u00e9volat pour vous. Notre \u00e9quipe passionn\u00e9e vous guideront et sauront offrir le soutien pour vous aider \u00e0 d\u00e9velopper de nouvelles comp\u00e9tences.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5af4e5 elementor-widget elementor-widget-button\" data-id=\"d5af4e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#benevole\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Je veux aider!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-247c104 e-con-full e-flex e-con e-parent\" data-id=\"247c104\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d1d06e4 e-con-full e-flex e-con e-child\" data-id=\"d1d06e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53052b4 elementor-widget elementor-widget-text-editor\" data-id=\"53052b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-media-text__content\">\n<h4 id=\"h-faire-un-difference\" class=\"wp-block-heading\">Faire un diff\u00e9rence<\/h4>\n<p>Les b\u00e9n\u00e9voles font une diff\u00e9rence chaque jour ici \u00e0 Nipissing Ouest. En partageant notre temps, nos comp\u00e9tences et notre enthousiasme entant que b\u00e9n\u00e9voles, nous contribuons \u00e0 une communaut\u00e9 dynamique et enrichissante.<\/p>\n<p>Ensemble, nous pouvons faire rayonner Cache Bay, Crystal Falls, D\u00e9saulniers, Field, Kipling, Lavigne, North Monetville, River Valley, Sturgeon Falls et Verner!<\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"https:\/\/westnipissing.ca\/wp-content\/uploads\/2025\/04\/AdobeStock_83643309_web-1024x683-1.jpg\" class=\"elementor-element elementor-element-d148e2a e-con-full e-flex e-con e-child\" data-id=\"d148e2a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d560d5 e-con-full e-flex e-con e-child\" data-id=\"0d560d5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-362c609 elementor-widget elementor-widget-heading\" data-id=\"362c609\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Postes de b\u00e9n\u00e9volat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba8f618 e-flex e-con-boxed e-con e-parent\" data-id=\"ba8f618\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec41162 elementor-widget elementor-widget-n-accordion\" data-id=\"ec41162\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2470\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2470\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Jardinage et am\u00e9nagement paysager <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M34.9 289.5l-22.2-22.2c-9.4-9.4-9.4-24.6 0-33.9L207 39c9.4-9.4 24.6-9.4 33.9 0l194.3 194.3c9.4 9.4 9.4 24.6 0 33.9L413 289.4c-9.5 9.5-25 9.3-34.3-.4L264 168.6V456c0 13.3-10.7 24-24 24h-32c-13.3 0-24-10.7-24-24V168.6L69.2 289.1c-9.3 9.8-24.8 10-34.3.4z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2470\" class=\"elementor-element elementor-element-28fd80f e-con-full e-flex e-con e-child\" data-id=\"28fd80f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-963986a elementor-widget elementor-widget-text-editor\" data-id=\"963986a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item active\">\n<div class=\"accordion-item-content\">\n<p><strong>Poste\u00a0<\/strong>: B\u00e9n\u00e9vole en jardinage et am\u00e9nagement paysager<\/p>\n<p><strong>Lieu<\/strong>\u00a0: Cache Bay, Crystal Falls, Field, River Valley, Sturgeon Falls, Verner<\/p>\n<p><strong>Sommaire<\/strong>\u00a0: Le\/la b\u00e9n\u00e9vole en jardinage et am\u00e9nagement paysager aide au jardinage et \u00e0 l\u2019am\u00e9nagement paysager dans le Nipissing Ouest. Ce poste travaillera avec le\/la responsable b\u00e9n\u00e9vole de l\u2019am\u00e9lioration et le d\u00e9partement des services communautaires pour fournir un soutien \u00e0 l\u2019entretien des parterres de fleurs et des parcs municipaux.<\/p>\n<p><strong>R\u00f4les et responsabilit\u00e9s:<\/strong><\/p>\n<ul>\n<li>Effectuer diverses t\u00e2ches d\u2019am\u00e9nagement paysager et de jardinage, y compris, mais sans s\u2019y limiter, le d\u00e9sherbage, la plantation, le paillage, l\u2019entretien, l\u2019arrosage et le nettoyage des plates-bandes, le soutien \u00e0 la peinture des infrastructures existantes, etc.<\/li>\n<li>Signalez \u00e0 votre responsable b\u00e9n\u00e9vole de l\u2019am\u00e9lioration tout changement dans l\u2019\u00e9tat des parterres de fleurs, des parcs et de son infrastructure.<\/li>\n<\/ul>\n<p><strong><br \/>Exigences:<\/strong><\/p>\n<ul>\n<li>\u00catre capable d\u2019effectuer des t\u00e2ches physiques telles que d\u00e9sherber, soulever des sacs de terre\/paillis, arroser, etc.<\/li>\n<li>Doit \u00eatre fiable, courtois et aimable avec le public<\/li>\n<li>Doit avoir un moyen de transport<\/li>\n<\/ul>\n<p><strong><br \/>Engagement de temps :<\/strong><\/p>\n<ul>\n<li>De d\u00e9but avril \u00e0 fin novembre<\/li>\n<li>Quelques fois par semaine ou au besoin (selon la m\u00e9t\u00e9o)<\/li>\n<li>Heures flexibles<\/li>\n<\/ul>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2471\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2471\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Responsable de l\u2019am\u00e9lioration paysag\u00e8re <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M34.9 289.5l-22.2-22.2c-9.4-9.4-9.4-24.6 0-33.9L207 39c9.4-9.4 24.6-9.4 33.9 0l194.3 194.3c9.4 9.4 9.4 24.6 0 33.9L413 289.4c-9.5 9.5-25 9.3-34.3-.4L264 168.6V456c0 13.3-10.7 24-24 24h-32c-13.3 0-24-10.7-24-24V168.6L69.2 289.1c-9.3 9.8-24.8 10-34.3.4z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2471\" class=\"elementor-element elementor-element-9733405 e-con-full e-flex e-con e-child\" data-id=\"9733405\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-550410a elementor-widget elementor-widget-text-editor\" data-id=\"550410a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Poste<\/strong>\u00a0: Responsable des b\u00e9n\u00e9voles pour l\u2019am\u00e9lioration paysag\u00e8re<\/p>\n<p><strong>Lieu<\/strong>\u00a0: Cache Bay, Crystal Falls, Field, River Valley<\/p>\n<p><strong>Sommaire<\/strong>\u00a0: Le\/la Responsable de l\u2019am\u00e9lioration agit comme agent de liaison pour les initiatives d\u2019am\u00e9lioration de la communaut\u00e9. Ce poste travaillera avec le d\u00e9partement des Services communautaires pour fournir un soutien \u00e0 l\u2019entretien des parterres de fleurs municipaux et des parcs. En tant que responsable, cette personne peut devoir coordonner le travail avec d\u2019autres b\u00e9n\u00e9voles et agir comme principal point de contact entre le groupe de b\u00e9n\u00e9voles d\u2019am\u00e9lioration et l\u2019agent de d\u00e9veloppement communautaire.<\/p>\n<p><strong>R\u00f4les et responsabilit\u00e9s:<\/strong><\/p>\n<ul>\n<li>Agir en tant que liaison entre le groupe d\u2019am\u00e9lioration et le d\u00e9partement des services communautaires de la municipalit\u00e9 de Nipissing Ouest.<\/li>\n<li>Effectuer diverses t\u00e2ches d\u2019am\u00e9nagement paysager et de jardinage, y compris, mais sans s\u2019y limiter, le d\u00e9sherbage, la plantation, le paillage, l\u2019entretien, l\u2019arrosage et le nettoyage des plates-bandes, le soutien \u00e0 la peinture des infrastructures existantes, etc.<\/li>\n<li>Signaler \u00e0 l\u2019agent de d\u00e9veloppement tout changement dans l\u2019\u00e9tat des plates-bandes, des parcs et de ses infrastructures.<\/li>\n<li>Coordonner diverses t\u00e2ches avec d\u2019autres b\u00e9n\u00e9voles.<\/li>\n<\/ul>\n<p><strong><br \/>Exigences:<\/strong><\/p>\n<ul>\n<li>Avoir de bonnes capacit\u00e9s de leadership<\/li>\n<li>\u00catre capable d\u2019effectuer des t\u00e2ches physiques telles que d\u00e9sherber, soulever des sacs de terre\/paillis, arroser, etc.<\/li>\n<li>Doit \u00eatre fiable, courtois et aimable avec le public<\/li>\n<li>Doit avoir un moyen de transport<\/li>\n<\/ul>\n<p><strong><br \/>Engagement de temps\u00a0:<\/strong><\/p>\n<ul>\n<li>De d\u00e9but avril \u00e0 fin novembre<\/li>\n<li>Trois fois par semaine ou au besoin (selon la m\u00e9t\u00e9o)<\/li>\n<li>Heures flexibles<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2472\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2472\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> \u00c9v\u00e9nements communautaires et programmation <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M34.9 289.5l-22.2-22.2c-9.4-9.4-9.4-24.6 0-33.9L207 39c9.4-9.4 24.6-9.4 33.9 0l194.3 194.3c9.4 9.4 9.4 24.6 0 33.9L413 289.4c-9.5 9.5-25 9.3-34.3-.4L264 168.6V456c0 13.3-10.7 24-24 24h-32c-13.3 0-24-10.7-24-24V168.6L69.2 289.1c-9.3 9.8-24.8 10-34.3.4z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2472\" class=\"elementor-element elementor-element-4ed4411 e-con-full e-flex e-con e-child\" data-id=\"4ed4411\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e3e20e elementor-widget elementor-widget-text-editor\" data-id=\"6e3e20e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Poste<\/strong>\u00a0: B\u00e9n\u00e9vole pour les \u00e9v\u00e9nements communautaires et la programmation<\/p>\n<p><strong>Lieu<\/strong>\u00a0: N\u2019importe o\u00f9 dans le Nipissing Ouest<\/p>\n<p><strong>Sommaire<\/strong>\u00a0: Le\/la B\u00e9n\u00e9vole charg\u00e9 des \u00e9v\u00e9nements et de la programmation communautaires travaillera avec le d\u00e9partement des Services communautaires pour fournir un soutien \u00e0 la planification et \u00e0 l\u2019ex\u00e9cution des \u00e9v\u00e9nements annuels et nouveaux organis\u00e9s par la Municipalit\u00e9 de Nipissing Ouest. Les \u00e9v\u00e9nements comprennent, mais sans s\u2019y limiter, le d\u00e9fil\u00e9 des lumi\u00e8res, la c\u00e9r\u00e9monie d\u2019illumination de l\u2019arbre, l\u2019Halloween en toute s\u00e9curit\u00e9 pour les enfants, les activit\u00e9s du week-end de la f\u00eate de la famille, les activit\u00e9s du cong\u00e9 de mars, la f\u00eate du Canada, les patins publics th\u00e9matiques, les c\u00e9r\u00e9monies de lever de drapeau, etc.<\/p>\n<p><strong>R\u00f4les et responsabilit\u00e9s:<\/strong><\/p>\n<ul>\n<li>Aider \u00e0 la planification et \u00e0 l\u2019ex\u00e9cution des \u00e9v\u00e9nements et de la programmation organis\u00e9s par la Municipalit\u00e9 de Nipissing Ouest<br \/>Assister \u00e0 des r\u00e9unions occasionnelles avec les agents de d\u00e9veloppement communautaire et d\u2019autres b\u00e9n\u00e9voles tout au long des phases de planification<\/li>\n<li>Promouvoir activement les \u00e9v\u00e9nements et la programmation municipale<br \/>Assister \u00e0 des \u00e9v\u00e9nements sur place et \u00eatre disponible pour aider avec des t\u00e2ches sp\u00e9cifiques<\/li>\n<li>Coordonner diverses t\u00e2ches avec d\u2019autres b\u00e9n\u00e9voles<\/li>\n<\/ul>\n<p><strong><br \/>Exigences:<\/strong><\/p>\n<ul>\n<li>Un chef d\u2019\u00e9quipe fiable<\/li>\n<li>Solides comp\u00e9tences en gestion de projet et\/ou en planification d\u2019\u00e9v\u00e9nements<\/li>\n<li>Un esprit critique avec une capacit\u00e9 \u00e0 effectuer plusieurs t\u00e2ches \u00e0 la fois et \u00e0 s\u2019adapter \u00e0 l\u2019\u00e9volution des priorit\u00e9s et des t\u00e2ches<\/li>\n<li>Excellentes aptitudes de communication<\/li>\n<li>Orient\u00e9 vers la communaut\u00e9 et passionn\u00e9 par le bien-\u00eatre de notre communaut\u00e9<\/li>\n<li>Aime travailler avec le public<\/li>\n<li>Bilinguisme est un atout<\/li>\n<\/ul>\n<p><strong><br \/>Engagement de temps\u00a0:<\/strong><\/p>\n<ul>\n<li>Toute l\u2019ann\u00e9e, car les \u00e9v\u00e9nements et la programmation se d\u00e9roulent tout au long de l\u2019ann\u00e9e<\/li>\n<li>Environ 5 heures par mois ou au besoin<\/li>\n<li>Les b\u00e9n\u00e9voles fixent leur propre horaire en fonction de leur disponibilit\u00e9<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5312dee elementor-widget elementor-widget-text-editor\" data-id=\"5312dee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"has-text-align-center\">Pour s\u2019assurer d\u2019un environnement diversifi\u00e9 et inclusif, lors de la s\u00e9lection des candidats, l\u2019\u00e9quipe des services communautaires prendra en compte des repr\u00e9sentants de diverses races, religions, sexes, identit\u00e9s ou expressions de genre, orientations sexuelles, origines nationales et handicaps.<\/p>\n<p class=\"has-text-align-center\">Les candidats choisis seront plac\u00e9s en fonction de comp\u00e9tences, de pr\u00e9f\u00e9rences et des besoins du groupe de b\u00e9n\u00e9voles municipal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f372ffd e-flex e-con-boxed e-con e-parent\" data-id=\"f372ffd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8a68a6 elementor-widget elementor-widget-text-editor\" data-id=\"e8a68a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"has-text-align-center\">Pour toutes questions ou commentaires, veuillez communiquer avec nous \u00e0\u00a0<a href=\"mailto:volunteer@westnipissing.ca\">volunteer@westnipissing.ca<\/a><\/p>\n<p class=\"has-text-align-center\">Pour vous joindre \u00e0 l\u2019\u00e9quipe, veuillez remplir le formulaire ci-dessous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48abf40 e-con-full e-flex e-con e-child\" data-id=\"48abf40\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ab58b2 elementor-widget elementor-widget-heading\" data-id=\"7ab58b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Devenir b\u00e9n\u00e9vole<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f5195e e-flex e-con-boxed e-con e-parent\" data-id=\"1f5195e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7105425 elementor-widget elementor-widget-menu-anchor\" data-id=\"7105425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"benevole\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17fce66 elementor-widget elementor-widget-shortcode\" data-id=\"17fce66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_64' >\n                        <div class='gform_heading'>\n                            <h2 class=\"gform_title\">Volunteer Contact Form \/ Formulaire de b\u00e9n\u00e9volat<\/h2>\n                            <p class='gform_description'><\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_64'  action='\/fr\/wp-json\/wp\/v2\/pages\/748' data-formid='64' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_64' class='gform_fields top_label form_sublabel_above description_above validation_below'><fieldset id=\"field_64_1\" class=\"gfield gfield--type-name gfield_contains_required field_sublabel_above gfield--no-description field_description_above field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Name \/ Nom<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_64_1'>\n                            \n                            <span id='input_64_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <label for='input_64_1_3' class='gform-field-label gform-field-label--type-sub '>Pr\u00e9nom<\/label>\n                                                    <input type='text' name='input_1.3' id='input_64_1_3' value=''   aria-required='true'    autocomplete=\"given-name\" \/>\n                                                <\/span>\n                            \n                            <span id='input_64_1_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                            <label for='input_64_1_6' class='gform-field-label gform-field-label--type-sub '>Nom<\/label>\n                                                            <input type='text' name='input_1.6' id='input_64_1_6' value=''   aria-required='true'    autocomplete=\"family-name\" \/>\n                                                        <\/span>\n                            \n                        <\/div><\/fieldset><fieldset id=\"field_64_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_above gfield--no-description field_description_above field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Email \/ Courriel<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container_email gform-grid-row' id='input_64_2_container'>\n                                <span id='input_64_2_1_container' class='ginput_left gform-grid-col gform-grid-col--size-auto'>\n                                    <label for='input_64_2' class='gform-field-label gform-field-label--type-sub '>Saisissez un e-mail<\/label>\n                                    <input class='' type='email' name='input_2' id='input_64_2' value=''    aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"email\"\/>\n                                <\/span>\n                                <span id='input_64_2_2_container' class='ginput_right gform-grid-col gform-grid-col--size-auto'>\n                                    <label for='input_64_2_2' class='gform-field-label gform-field-label--type-sub '>Confirmez l\u2019e-mail<\/label>\n                                    <input class='' type='email' name='input_2_2' id='input_64_2_2' value=''    aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"email\"\/>\n                                <\/span>\n                                <div class='gf_clear gf_clear_complex'><\/div>\n                            <\/div><\/fieldset><div id=\"field_64_6\" class=\"gfield gfield--type-phone gfield--width-full field_sublabel_above gfield--no-description field_description_above field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_64_6'>Phone \/ T\u00e9l\u00e9phone<\/label><div class='ginput_container ginput_container_phone'><input name='input_6' id='input_64_6' type='tel' value='' class='large'    aria-invalid=\"false\"   \/><\/div><\/div><fieldset id=\"field_64_4\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield_contains_required field_sublabel_above gfield--has-description field_description_above field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >What type of volunteering are you interested in? \/ Quel r\u00f4le de b\u00e9n\u00e9volat vous int\u00e9resse?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/legend><div class='gfield_description' id='gfield_description_64_4'>Please check all that apply \/ Veuillez cocher toutes les options qui s'appliquent<\/div><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_64_4'><div class='gchoice gchoice_64_4_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_4.1' type='checkbox'  value='Gardening and Landscaping \/ Jardinage et am\u00e9nagement paysager'  id='choice_64_4_1'   aria-describedby=\"gfield_description_64_4\"\/>\n\t\t\t\t\t\t\t\t<label for='choice_64_4_1' id='label_64_4_1' class='gform-field-label gform-field-label--type-inline'>Gardening and Landscaping \/ Jardinage et am\u00e9nagement paysager<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_64_4_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_4.2' type='checkbox'  value='Community Enhancement Lead \/ Responsable de l\u2019am\u00e9lioration paysag\u00e8re'  id='choice_64_4_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_64_4_2' id='label_64_4_2' class='gform-field-label gform-field-label--type-inline'>Community Enhancement Lead \/ Responsable de l\u2019am\u00e9lioration paysag\u00e8re<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_64_4_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_4.3' type='checkbox'  value='Community Events and Programming \/ \u00c9v\u00e9nements communautaires et programmation'  id='choice_64_4_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_64_4_3' id='label_64_4_3' class='gform-field-label gform-field-label--type-inline'>Community Events and Programming \/ \u00c9v\u00e9nements communautaires et programmation<\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><fieldset id=\"field_64_5\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield_contains_required field_sublabel_above gfield--has-description field_description_above field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >In what area(s) are you interested in working? \/ Dans quel(s) coin(s) pr\u00e9f\u00e9rez-vous participer?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/legend><div class='gfield_description' id='gfield_description_64_5'>Please check all that apply \/ Veuillez cocher toutes les options qui s'appliquent<\/div><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_64_5'><div class='gchoice gchoice_64_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Cache Bay'  id='choice_64_5_1'   aria-describedby=\"gfield_description_64_5\"\/>\n\t\t\t\t\t\t\t\t<label for='choice_64_5_1' id='label_64_5_1' class='gform-field-label gform-field-label--type-inline'>Cache Bay<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_64_5_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.2' type='checkbox'  value='Crystal Falls'  id='choice_64_5_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_64_5_2' id='label_64_5_2' class='gform-field-label gform-field-label--type-inline'>Crystal Falls<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_64_5_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.3' type='checkbox'  value='Field \/ Desaulniers'  id='choice_64_5_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_64_5_3' id='label_64_5_3' class='gform-field-label gform-field-label--type-inline'>Field \/ Desaulniers<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_64_5_4'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.4' type='checkbox'  value='Lavigne \/ North Monetville'  id='choice_64_5_4'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_64_5_4' id='label_64_5_4' class='gform-field-label gform-field-label--type-inline'>Lavigne \/ North Monetville<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_64_5_5'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.5' type='checkbox'  value='Sturgeon Falls'  id='choice_64_5_5'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_64_5_5' id='label_64_5_5' class='gform-field-label gform-field-label--type-inline'>Sturgeon Falls<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_64_5_6'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.6' type='checkbox'  value='Verner'  id='choice_64_5_6'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_64_5_6' id='label_64_5_6' class='gform-field-label gform-field-label--type-inline'>Verner<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_64_5_7'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.7' type='checkbox'  value='River Valley \/ Kipling'  id='choice_64_5_7'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_64_5_7' id='label_64_5_7' class='gform-field-label gform-field-label--type-inline'>River Valley \/ Kipling<\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><div id=\"field_64_7\" class=\"gfield gfield--type-html gfield_html gfield_html_formatted field_sublabel_above gfield--no-description field_description_above field_validation_below gfield_visibility_visible\"  ><div style=\"width:100%; height:40px\"> <\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_64' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Submit'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_64' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_64' id='gform_theme_64' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_64' id='gform_style_settings_64' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_64' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='64' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='CAD' value='vUpogMTOGsba6Ti8LnHEmXZzButS\/mDmiUdVlWhDUtGjprNyLOj49HhzfaMsuXdN8F4p9a8bGCatVP5Av4MpR5LwxF6j93NPQeaQ3emLt5TR8hQ=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_64' value='WyJ7XCI0LjFcIjpcImI2NjdkNDA5NzNjMGI5NzA5MjhiMDM5ZWM0YzE3YzkwXCIsXCI0LjJcIjpcIjk4NWZhMzE0ODRkNTg0MTIxMGMzNWExZjdhMDE2ODFiXCIsXCI0LjNcIjpcImFiNTlhYWE1YjkwNTdhNTIxOTc4MmIwYTEyYmY4ZWVlXCIsXCI1LjFcIjpcImYzNGIyMjVlYWJiYWRlMWQ2ZjRhYjFlYjRmNGQzOTE4XCIsXCI1LjJcIjpcIjE3ZWM1OTIzZGQ1MzU5YjFmMzFkYmJiYjBjZjRlOGI3XCIsXCI1LjNcIjpcIjlhMGY0Y2JjZWU0NmE0N2M0NmNlOWM1MTc3OGQ0M2M0XCIsXCI1LjRcIjpcIjMwNjRhMjZlN2UwZDIyNjlkOGQwNmE2OGVkNjJkMTA4XCIsXCI1LjVcIjpcIjUyMWI0ZjM0YzExNTVjYjI3ZDQzOTUwZDYwMGViNjJkXCIsXCI1LjZcIjpcIjQ0NTMwNDY4YTI2MzcyZDQzNDIxNWZiNTg4MTJmZGJhXCIsXCI1LjdcIjpcIjg5MDUyOWY0MGEyMDliZTYwYzZmYzk4ZWQ0YzlmM2JhXCJ9IiwiYjZkNGFlMWQ4MmI3NTBlMjJlNjMwZTMwNTdjNGNhNmYiXQ==' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_64' id='gform_target_page_number_64' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_64' id='gform_source_page_number_64' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 64, 'https:\/\/www.westnipissing.ca\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_64').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_64');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_64').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_64').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_64').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_64').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_64').val();gformInitSpinner( 64, 'https:\/\/www.westnipissing.ca\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [64, current_page]);window['gf_submitting_64'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_64').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [64]);window['gf_submitting_64'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_64').text());}else{jQuery('#gform_64').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"64\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_64\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_64\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_64\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 64, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Participez et invitez des amis! Que vous soyez un \u00e9tudiant du secondaire souhaitant accomplir des heures communautaires ou quelqu\u2019un \u00e0 la retraite qui aimerait s\u2019impliquer dans la communaut\u00e9, nous avons [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":50975,"parent":715,"menu_order":14,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"class_list":["post-748","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Devenez b\u00e9n\u00e9vole - West Nipissing Ouest<\/title>\n<meta name=\"description\" content=\"\u00cates-vous int\u00e9ress\u00e9 \u00e0 faire du b\u00e9n\u00e9volat avec la Municipalit\u00e9 de Nipissing Ouest? Il existe de nombreuses fa\u00e7ons de s&#039;impliquer. Les \u00e9l\u00e8ves du secondaire et les adultes de tous \u00e2ges sont encourag\u00e9s de se joindre \u00e0 nous. Vous pouvez \u00e9galement vous inscrire en famille.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Devenez b\u00e9n\u00e9vole\" \/>\n<meta property=\"og:description\" content=\"\u00cates-vous int\u00e9ress\u00e9 \u00e0 faire du b\u00e9n\u00e9volat avec la Municipalit\u00e9 de Nipissing Ouest? Il existe de nombreuses fa\u00e7ons de s&#039;impliquer. Les \u00e9l\u00e8ves du secondaire et les adultes de tous \u00e2ges sont encourag\u00e9s de se joindre \u00e0 nous. Vous pouvez \u00e9galement vous inscrire en famille.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/\" \/>\n<meta property=\"og:site_name\" content=\"West Nipissing Ouest\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MunicipalityofWestNipissing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T14:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.westnipissing.ca\/wp-content\/uploads\/2025\/05\/AdobeStock_273014615_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2240\" \/>\n\t<meta property=\"og:image:height\" content=\"1234\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@West_Nipissing\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/culture-loisirs\\\/benevole\\\/\",\"url\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/culture-loisirs\\\/benevole\\\/\",\"name\":\"Devenez b\u00e9n\u00e9vole - West Nipissing Ouest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/culture-loisirs\\\/benevole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/culture-loisirs\\\/benevole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.westnipissing.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/AdobeStock_273014615_web.jpg\",\"datePublished\":\"2023-05-19T18:55:00+00:00\",\"dateModified\":\"2026-05-12T14:13:00+00:00\",\"description\":\"\u00cates-vous int\u00e9ress\u00e9 \u00e0 faire du b\u00e9n\u00e9volat avec la Municipalit\u00e9 de Nipissing Ouest? Il existe de nombreuses fa\u00e7ons de s'impliquer. Les \u00e9l\u00e8ves du secondaire et les adultes de tous \u00e2ges sont encourag\u00e9s de se joindre \u00e0 nous. Vous pouvez \u00e9galement vous inscrire en famille.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/culture-loisirs\\\/benevole\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/culture-loisirs\\\/benevole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/culture-loisirs\\\/benevole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.westnipissing.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/AdobeStock_273014615_web.jpg\",\"contentUrl\":\"https:\\\/\\\/www.westnipissing.ca\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/AdobeStock_273014615_web.jpg\",\"width\":2240,\"height\":1234,\"caption\":\"Hands of group friends in the shape of a heart against the sunset. Love and relationship friendship concept\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/culture-loisirs\\\/benevole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture et loisirs\",\"item\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/culture-loisirs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Devenez b\u00e9n\u00e9vole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/\",\"name\":\"West Nipissing Ouest\",\"description\":\"Find your Joie de vivre in West Nipissing.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/#organization\",\"name\":\"West Nipissing Ouest\",\"url\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.westnipissing.ca\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/site-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.westnipissing.ca\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/site-logo.jpg\",\"width\":700,\"height\":225,\"caption\":\"West Nipissing Ouest\"},\"image\":{\"@id\":\"https:\\\/\\\/www.westnipissing.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MunicipalityofWestNipissing\\\/\",\"https:\\\/\\\/x.com\\\/West_Nipissing\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCG6HWMXnA-RBiH-UdZVClHg\"],\"description\":\"Municipality of West Nipissing\",\"email\":\"info@westnipissing.ca\",\"telephone\":\"705-753-2250\",\"legalName\":\"Municipality of West Nipissing\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Devenez b\u00e9n\u00e9vole - West Nipissing Ouest","description":"\u00cates-vous int\u00e9ress\u00e9 \u00e0 faire du b\u00e9n\u00e9volat avec la Municipalit\u00e9 de Nipissing Ouest? Il existe de nombreuses fa\u00e7ons de s'impliquer. Les \u00e9l\u00e8ves du secondaire et les adultes de tous \u00e2ges sont encourag\u00e9s de se joindre \u00e0 nous. Vous pouvez \u00e9galement vous inscrire en famille.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/","og_locale":"fr_FR","og_type":"article","og_title":"Devenez b\u00e9n\u00e9vole","og_description":"\u00cates-vous int\u00e9ress\u00e9 \u00e0 faire du b\u00e9n\u00e9volat avec la Municipalit\u00e9 de Nipissing Ouest? Il existe de nombreuses fa\u00e7ons de s'impliquer. Les \u00e9l\u00e8ves du secondaire et les adultes de tous \u00e2ges sont encourag\u00e9s de se joindre \u00e0 nous. Vous pouvez \u00e9galement vous inscrire en famille.","og_url":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/","og_site_name":"West Nipissing Ouest","article_publisher":"https:\/\/www.facebook.com\/MunicipalityofWestNipissing\/","article_modified_time":"2026-05-12T14:13:00+00:00","og_image":[{"width":2240,"height":1234,"url":"https:\/\/www.westnipissing.ca\/wp-content\/uploads\/2025\/05\/AdobeStock_273014615_web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@West_Nipissing","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/","url":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/","name":"Devenez b\u00e9n\u00e9vole - West Nipissing Ouest","isPartOf":{"@id":"https:\/\/www.westnipissing.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/#primaryimage"},"image":{"@id":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.westnipissing.ca\/wp-content\/uploads\/2025\/05\/AdobeStock_273014615_web.jpg","datePublished":"2023-05-19T18:55:00+00:00","dateModified":"2026-05-12T14:13:00+00:00","description":"\u00cates-vous int\u00e9ress\u00e9 \u00e0 faire du b\u00e9n\u00e9volat avec la Municipalit\u00e9 de Nipissing Ouest? Il existe de nombreuses fa\u00e7ons de s'impliquer. Les \u00e9l\u00e8ves du secondaire et les adultes de tous \u00e2ges sont encourag\u00e9s de se joindre \u00e0 nous. Vous pouvez \u00e9galement vous inscrire en famille.","breadcrumb":{"@id":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/#primaryimage","url":"https:\/\/www.westnipissing.ca\/wp-content\/uploads\/2025\/05\/AdobeStock_273014615_web.jpg","contentUrl":"https:\/\/www.westnipissing.ca\/wp-content\/uploads\/2025\/05\/AdobeStock_273014615_web.jpg","width":2240,"height":1234,"caption":"Hands of group friends in the shape of a heart against the sunset. Love and relationship friendship concept"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/benevole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.westnipissing.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Culture et loisirs","item":"https:\/\/www.westnipissing.ca\/fr\/culture-loisirs\/"},{"@type":"ListItem","position":3,"name":"Devenez b\u00e9n\u00e9vole"}]},{"@type":"WebSite","@id":"https:\/\/www.westnipissing.ca\/fr\/#website","url":"https:\/\/www.westnipissing.ca\/fr\/","name":"West Nipissing Ouest","description":"Find your Joie de vivre in West Nipissing.","publisher":{"@id":"https:\/\/www.westnipissing.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.westnipissing.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.westnipissing.ca\/fr\/#organization","name":"West Nipissing Ouest","url":"https:\/\/www.westnipissing.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.westnipissing.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.westnipissing.ca\/wp-content\/uploads\/2024\/04\/site-logo.jpg","contentUrl":"https:\/\/www.westnipissing.ca\/wp-content\/uploads\/2024\/04\/site-logo.jpg","width":700,"height":225,"caption":"West Nipissing Ouest"},"image":{"@id":"https:\/\/www.westnipissing.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MunicipalityofWestNipissing\/","https:\/\/x.com\/West_Nipissing","https:\/\/www.youtube.com\/channel\/UCG6HWMXnA-RBiH-UdZVClHg"],"description":"Municipality of West Nipissing","email":"info@westnipissing.ca","telephone":"705-753-2250","legalName":"Municipality of West Nipissing"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:45:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/pages\/748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/comments?post=748"}],"version-history":[{"count":1,"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/pages\/748\/revisions"}],"predecessor-version":[{"id":69144,"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/pages\/748\/revisions\/69144"}],"up":[{"embeddable":true,"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/pages\/715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/media\/50975"}],"wp:attachment":[{"href":"https:\/\/www.westnipissing.ca\/fr\/wp-json\/wp\/v2\/media?parent=748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}